{"id":2975,"date":"2015-03-01T15:26:05","date_gmt":"2015-03-01T14:26:05","guid":{"rendered":"http:\/\/strubbelmiez.de\/?p=2975"},"modified":"2015-03-01T15:26:05","modified_gmt":"2015-03-01T14:26:05","slug":"erster-fruehlingsjubel","status":"publish","type":"post","link":"http:\/\/strubbelmiez.de\/index.php\/erster-fruehlingsjubel\/","title":{"rendered":"erster  Fr\u00fchlingsjubel &#8230;"},"content":{"rendered":"<p><strong>Der Fr\u00fchling winkt schon ein bisschen.<\/strong>\u00a0 Es ist schon eine Weile sch\u00f6n mild und die Sonne lacht uns entgegen. Drinnen motiviert es zum Putzen und Dekorieren und drau\u00dfen tut die frische Luft gleich noch mal so gut und verbessert die Laune immens. Da wird die Zeit und Lust zum Stricken gleich wieder d\u00fcnner \ud83d\ude06 dann wird im Park, ein paar Meter von den S\u00e4ufern entfernt gesessen und gelesen, das bringt auch wieder ein paar Pigmente auf die Haut.<\/p>\n<p>In den Onlinezeitschriften diskutiert man wieder \u00fcber &#8222;Armut&#8220;, vor allem bei Kindern. Ja, nur ein Handy und nur wenige Spiele f\u00fcr die Konsole kann seit Jahren schon echt hart sein. Dort wo wirklich Armut herrscht und es ums blanke \u00dcberleben geht, lacht man sich \u00fcber diese \u201eProbleme\u201c eher tot, wenn man da nicht gerade verhungert.<\/p>\n<p>Und noch ein Reizthema geht durch Deutschland, die Impfung mal wieder. Nun hei\u00dft es, es w\u00e4re ein Kind an Masern gestorben. Nat\u00fcrlich beharken sich Impfbef\u00fcrworter und die Gegner. Bei einem th\u00fcringischen Radiosender findet man es sogar \u201ekrass\u201c (so im Kommentar unter meiner Meinung), dass man Geld bietet, um auch ungeimpfte Kinder unterzubekommen und man hoffte, dass ich mich sozusagen \u201ebestechen\u201c lasse. Was ist so ungew\u00f6hnlich dran? Richtig finde ich es auch nicht und ich habe mich darauf auch nicht eingelassen, auch wenn uns die Stadt mit 1-3 Eur\/ Stunde abgespeist hat und die Schwarzarbeit ordentlich bl\u00fchen lie\u00df. Aber ca. 5 Euro mehr und selbst wenn es mehr gewesen w\u00e4re, sch\u00fctzen die Gesundheit anderer auch nicht. Das w\u00e4re so ein Kapitel namens \u201eWenn einfach gestrickte und geizige Leute auf ebensolche hoffen\u201c wert! Zum Gl\u00fcck muss ich mich damit nicht mehr befassen und nur noch auf meinen eigenen Impfschutz achten, damit ich da nix mehr vert\u00fcdele, denn schnell ist es vergessen, die Impfungen aufzufrischen. Aber Termin steht ja. Hei\u00dft also, ich lasse mich immer noch impfen. Risikolos ist nichts, aber stellen wir mal den Nutzen gegen\u00fcber.<\/p>\n<p>Und wer Lachtr\u00e4nen mag, liest sich mal bei den typischen Weiberzeitschriften in den Fanseiten durch. Herrlich, sage ich Euch. Der derzeitige Kracher ist die Frage, warum sich Frauen zu enge Sachen tragen und sie dann Abdr\u00fccke davon auf der Haut haben. Ich habe mir mal ein paar Antworten der kommentierenden Weibchen durchgelesen und bin \u00fcber das oft niedrige Niveau wenig \u00fcberrascht. Sinngem\u00e4\u00df hei\u00dft es bei vielen Antworten, dass Frauen ja auch vorgemacht wird, wie sie sich anzuziehen h\u00e4tten und dass Frauen daf\u00fcr nichts k\u00f6nnen. Au\u00dferdem wird man ab Gr\u00f6\u00dfe 38 schon als fett bezeichnet und da muss man ja unbedingt engere Sachen anziehen. Und dann lese ich die Antwort eines Mannes, der da schreibt, egal wie toll die Jeans aussieht und wie eng die sitzen soll, fett bleibt fett. Ich habe langgelegen vor Lachen! Nat\u00fcrlich erbo\u00dften sich einige Weibchen und ich setze allem noch die Krone auf und schreibe, dass ich ihm auch als Frau beipflichte und einer Dame erkl\u00e4rte ich, dass man sich nicht durch irgendwelche Bl\u00e4ttchen beeinflussen lassen muss. Wer seinen Kopf f\u00fcr mehr nutzt als nur zum Haare schneiden, kauft sich einfach Sachen, die sitzen und die Person gut kleiden. Und auch f\u00fcr die st\u00e4mmige Statur gibt es doch sch\u00f6ne Sachen, die sehr sch\u00f6n fallen und vorteilhaft wirken. Und ich kenne meine \u00dcbergewichtszeiten noch zu gut und das war genau zur Wendezeit, als das Angebot noch nicht so vielf\u00e4ltig war. M\u00e4dels, kleidet Euch bequem, engt Euch nicht ein und spart das Geld f\u00fcr Weiberzeitschriften. Rezepte und sonstige Tipps gibt\u2019s gen\u00fcgend im Netz f\u00fcr 0 Euro und 0 Cent. Nehmt lieber jemanden mit, der ehrlich seine Meinung sagt und Vorschl\u00e4ge bringt, was Euch gut kleidet. Aber wohl f\u00fchlen ist das Wichtigste, ganz egal, welche Statur man hat.<\/p>\n<p>Und damit das Verbraucherherzchen wieder h\u00fcpfen kann, gibt\u2019s wie gewohnt den Werbeblock: <em>\u201eIch will Marieeeeeeeeeeee!\u201c<\/em> schreit es uns in einem Spot f\u00fcr irgendeine Markenhose entgegen. Herrje, was eine schwarze und sicher auch nicht \u00fcbel geschnittene Hose so bewirken soll, wei\u00df ich noch nicht so. Und da man noch immer sehr f\u00fcr Erk\u00e4ltungszeugs wirbt, bietet sich uns zus\u00e4tzlich auch die Werbung f\u00fcr Warzenzeugs. Und bei einem angeblich Bakterien abt\u00f6tenden Duschgel verspricht man uns auch zus\u00e4tzlich l\u00e4ngerer Frische, sogar als \u201eDuschinnovation\u201c, boha! Und weil das nicht reicht, muss man seine ganze Bude desinfizieren, indem man ein Zellstoffk\u00fcchentuch nimmt, auf den Spender dr\u00fcckt und die K\u00fcchenoberfl\u00e4chen abwischt. Nat\u00fcrlich m\u00fcssen gerade in der Erk\u00e4ltungszeit noch mindestens alle T\u00fcrklinken von Keim befreit werden und mein schlichter Tipp ist: einfach \u00f6fter H\u00e4nde waschen, vor allem, wenn man keine Taschent\u00fccher beim Niesen und Husten benutzt. So etwas ist ja sehr verbreitet und ekelhaft! Aber wem sagen wir das? Und es gibt die Taschent\u00fccher sogar <em>\u201esoft, softer\u2026 \u201e.<\/em> Mahlzeit.<\/p>\n<p><strong>In diesem Sinne:<\/strong>\u00a0 Lockt den Fr\u00fchling mal noch ein bisschen, \u00f6ffnet Fenster und Herzchen und schmei\u00dft die Weiberzeitschrift in Kisten, die ihr noch f\u00fcr Geschirr oder Deko abpolstern wollt \ud83d\ude06 Prost* kalten Pfeffi-Honig-Tee.<\/p>\n<div id=\"wp_fb_like_button\" style=\"margin:5px 0;float:none;height:100px;\"><script src=\"http:\/\/connect.facebook.net\/en_US\/all.js#xfbml=1\"><\/script><fb:like href=\"http:\/\/strubbelmiez.de\/index.php\/erster-fruehlingsjubel\/\" send=\"true\" layout=\"standard\" width=\"450\" show_faces=\"true\" font=\"arial\" action=\"like\" colorscheme=\"light\"><\/fb:like><\/div>","protected":false},"excerpt":{"rendered":"<p>Der Fr\u00fchling winkt schon ein bisschen.\u00a0 Es ist schon eine Weile sch\u00f6n mild und die Sonne lacht uns entgegen. Drinnen motiviert es zum Putzen und Dekorieren und drau\u00dfen tut die frische Luft gleich noch mal so gut und verbessert die Laune immens. Da wird die Zeit und Lust zum Stricken gleich wieder d\u00fcnner \ud83d\ude06 dann &hellip; <a href=\"http:\/\/strubbelmiez.de\/index.php\/erster-fruehlingsjubel\/\" class=\"more-link\"><span class=\"screen-reader-text\">erster  Fr\u00fchlingsjubel &#8230;<\/span> weiterlesen <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[1],"tags":[],"class_list":["post-2975","post","type-post","status-publish","format-standard","hentry","category-allgemein"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p2ijNL-LZ","jetpack-related-posts":[],"_links":{"self":[{"href":"http:\/\/strubbelmiez.de\/index.php\/wp-json\/wp\/v2\/posts\/2975","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/strubbelmiez.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/strubbelmiez.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/strubbelmiez.de\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/strubbelmiez.de\/index.php\/wp-json\/wp\/v2\/comments?post=2975"}],"version-history":[{"count":1,"href":"http:\/\/strubbelmiez.de\/index.php\/wp-json\/wp\/v2\/posts\/2975\/revisions"}],"predecessor-version":[{"id":2976,"href":"http:\/\/strubbelmiez.de\/index.php\/wp-json\/wp\/v2\/posts\/2975\/revisions\/2976"}],"wp:attachment":[{"href":"http:\/\/strubbelmiez.de\/index.php\/wp-json\/wp\/v2\/media?parent=2975"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/strubbelmiez.de\/index.php\/wp-json\/wp\/v2\/categories?post=2975"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/strubbelmiez.de\/index.php\/wp-json\/wp\/v2\/tags?post=2975"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}