{"id":3011,"date":"2015-04-12T17:44:00","date_gmt":"2015-04-12T15:44:00","guid":{"rendered":"http:\/\/strubbelmiez.de\/?p=3011"},"modified":"2015-04-21T17:46:17","modified_gmt":"2015-04-21T15:46:17","slug":"endlich-fruehlingstrubel","status":"publish","type":"post","link":"http:\/\/strubbelmiez.de\/index.php\/endlich-fruehlingstrubel\/","title":{"rendered":"endlich Fr\u00fchlingstrubel &#8230;"},"content":{"rendered":"<p><strong>Endlich hat sich der Fr\u00fchling gesetzt,<\/strong> zwischendurch stand der ja schon \u00f6fter auf und ging ein paar Schritte weg. Ich verstehe es hier auch \ud83d\ude06 . Nun k\u00f6nnen die Wintersachen wirklich weg \u2013 juchuuuuuuuuu ! <\/p>\n<p>Nat\u00fcrlich sind mir wieder ein paar Modekracher vor meine nassen \u00c4uglein (vor Lachen) geraten. Man tr\u00e4gt jetzt nur noch Kreisjacken und \u201eSeelenw\u00e4rmer\u201c. H\u00fcbsch sind die Dinger auch anzusehen und selbst gemacht ist immer individuell. Aber es gibt sie auch hier und dort im Angebot. Hm, ich bin fast 40 und kriege langsam Angst.  Ich glaube, ich bleibe noch bis zur letzten Kiste ein J\u00e4ckchenmuffel. Auf einer anderen Seite , bei der \u201eModefl\u00fcsterin\u201c gibt\u2019s jetzt Tipps f\u00fcr Sneaker. Manche Kombis sehen echt nicht \u00fcbel aus und bequem sind sie auch, wenn man die richtigen erwischt. Andere Kombis zu Kleidern sind  mir nicht so meins, aber ist alles Geschmackssache. Ich muss auch noch welche \u201ejagen\u201c, wir sehen uns dann in der Herrenabteilung \ud83d\ude06 <\/p>\n<p>Ich lache ja gern \u00fcber Trends und vor allem \u00fcber Weibchenzeitungen. Ich bekam einen Gutschein f\u00fcr ein Bl\u00e4ttchen und nein, es h\u00e4ngt kein Abo dran. Ich guckte also, ob es eine Zeitschrift mit Zubeh\u00f6r incl. gibt. Gibt es auch aber  ich muss den genauen Namen und Ausgaben suchen. Und da kommt nat\u00fcrlich erstmal eine gro\u00dfe Auswahl vor meine schon etwas faltigen \u00c4uglein. <em>\u201eDas Journal f\u00fcr die digitale Dame\u201c<\/em> \u00e4hm\u2026.<em>\u201cdigitale Dame\u201c<\/em> ?! Gut, ich bin nicht mal eine Dame, aber auch noch \u201edigital\u201c? Hey, ich bin echt wie alle Frauen auch \ud83d\ude2f und programmieren lasse ich mich auch nicht. Au\u00dferdem ists mir eh schnurz, welche Di\u00e4t gerade \u201eIN\u201c oder \u201eOut\u201c ist, was M\u00e4nner m\u00f6gen und was nicht, wie wir uns zu kleiden und zu stylen haben und zu guter Letzt, was wir zu kochen oder zu backen h\u00e4tten. Und ja, ich bin echt eine Frau,  halt mit Ecken und Kanten \ud83d\ude06 und in Newslettern kriege ich Antifaltencremes angeboten. Dankeeeeeeeeee\u2026<\/p>\n<p>F\u00fcr das kleine \u201eOmmmm\u2026.!\u201c zwischendurch wird tats\u00e4chlich mal herumgesessen, ich fasse es nicht! K\u00fchlung auf die F\u00fc\u00dfe und  losnadeln. F\u00fcr den Tag ist das nix, ich bleibe ein Hibbel, auch wenn ich nicht mehr so kann. Danke an gewisse Herren und Damen Doktoren. Aber man macht das Beste draus, weiter ackern, damit es wieder hinhaut und wenigstens im Sitzen produktiv sein. B\u00fcro ist doch was Feines *h\u00fcstel*. <\/p>\n<p>Und neuerdings seit Bestellung eines E-Books bekomme ich ja Newsletter \u00fcbers Gl\u00fccklichsein, das w\u00e4re was f\u00fcr die einheimische Bev\u00f6lkerung, die \u00fcber alles und jeden klagt \ud83d\ude06 und \u00fcber harmlose \u00e4nderbare Dinge. Aber statt etwas selbst zu \u00e4ndern, wie es in der Macht steht, ist n\u00f6rgeln bequemer, gelle? Aber was reden  wir hier? Hilft auch nix. Selbst unser roter MP klagt jetzt \u00fcber Bedrohungen, kriegt  mal ein sachliches Briefchen, aber reicht auch nicht, bitte Geld nachsenden, dann kann er wieder l\u00e4cheln, anders kriegt man diese  V\u00f6gel nicht! Und MP sind nicht die einzigen Leute, die irgendwo und irgendwie bedroht sind und sie sind auch nicht die Nabel der Welt. Unsereins macht das mit entsprechenden Stellen aus, sei es die Polente oder Anw\u00e4lte und manche m\u00fcssen sich ihr Mitleid halt \u00fcber die Medien holen. Meins h\u00e4lt sich in Grenzen, dessen H\u00e4ufchen war auch nie besser.<\/p>\n<p>Und damit das Vebraucherherzchen wieder informiert ist, gibt\u2019s nat\u00fcrlich wieder den <strong>Werbeblock:<\/strong> Kommen wir mal zu grenzenlosem Genuss. Da r\u00fchren bei 2 Spots Typen in der Schokolade rum, freuen sich dabei und wenn das St\u00fccke fertig ist, wird\u2019s noch mal in die H\u00e4nde genommen und be\u00e4ugt \u2013 iiiiiiiiiiiiiih ! Der Knaller war ja die Osterwerbung einer Firma, die ja auch ewig grinsende Typen mit Schokoladenp\u00f6tten zeigt. Und er zaubert extra einen Schokohasen und ja woran erkennt man die Marke? <em>\u201eAm Gl\u00f6ckchen!\u201c<\/em> so  die Antwort des Kindes. Nicht doch etwa  die Wahnsinnsqualit\u00e4t. Die verpassen sich selbst Eigentore, das nenne ich Humor. Und wir sehen f\u00fcr eine Parf\u00fcmwerbung eine Frau, vielleicht gar ein Model, ich kenne mich damit nicht aus und sie wispert, dass sie den Duft wie wundersch\u00f6ne Kleidung tragen w\u00fcrde. Hm, wenigstens ist Duft nicht unbequem und zwickt an allen m\u00f6glichen Stellen. Wir wissen ja aus einem Spot f\u00fcr eine Klamottenkette, dass Mode ja  Druck macht, sie dr\u00fcckt hier und dort. Und dann serviert man uns \u00fcberteuertes Zeug. <\/p>\n<p><strong>In diesem Sinne:<\/strong> lieber was Bequemes, auch f\u00fcr schicke Anl\u00e4sse, mittlere Preisklasse hat auch meist gute Qualit\u00e4t  und wer Mitleid braucht, kann k\u00fcnftig ja den Jammertalkurier daf\u00fcr nutzen, die sind darin gut ge\u00fcbt, alles ohne zu hinterfragen zu ver\u00f6ffentlichen. *Prost*  restlichen Sekt, der hat null Umdrehungen \ud83d\ude00 <\/p>\n<div id=\"wp_fb_like_button\" style=\"margin:5px 0;float:none;height:100px;\"><script src=\"http:\/\/connect.facebook.net\/en_US\/all.js#xfbml=1\"><\/script><fb:like href=\"http:\/\/strubbelmiez.de\/index.php\/endlich-fruehlingstrubel\/\" send=\"true\" layout=\"standard\" width=\"450\" show_faces=\"true\" font=\"arial\" action=\"like\" colorscheme=\"light\"><\/fb:like><\/div>","protected":false},"excerpt":{"rendered":"<p>Endlich hat sich der Fr\u00fchling gesetzt, zwischendurch stand der ja schon \u00f6fter auf und ging ein paar Schritte weg. Ich verstehe es hier auch \ud83d\ude06 . Nun k\u00f6nnen die Wintersachen wirklich weg \u2013 juchuuuuuuuuu ! Nat\u00fcrlich sind mir wieder ein paar Modekracher vor meine nassen \u00c4uglein (vor Lachen) geraten. Man tr\u00e4gt jetzt nur noch Kreisjacken &hellip; <a href=\"http:\/\/strubbelmiez.de\/index.php\/endlich-fruehlingstrubel\/\" class=\"more-link\"><span class=\"screen-reader-text\">endlich Fr\u00fchlingstrubel &#8230;<\/span> weiterlesen <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[1],"tags":[],"class_list":["post-3011","post","type-post","status-publish","format-standard","hentry","category-allgemein"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p2ijNL-Mz","jetpack-related-posts":[],"_links":{"self":[{"href":"http:\/\/strubbelmiez.de\/index.php\/wp-json\/wp\/v2\/posts\/3011","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/strubbelmiez.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/strubbelmiez.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/strubbelmiez.de\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/strubbelmiez.de\/index.php\/wp-json\/wp\/v2\/comments?post=3011"}],"version-history":[{"count":1,"href":"http:\/\/strubbelmiez.de\/index.php\/wp-json\/wp\/v2\/posts\/3011\/revisions"}],"predecessor-version":[{"id":3012,"href":"http:\/\/strubbelmiez.de\/index.php\/wp-json\/wp\/v2\/posts\/3011\/revisions\/3012"}],"wp:attachment":[{"href":"http:\/\/strubbelmiez.de\/index.php\/wp-json\/wp\/v2\/media?parent=3011"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/strubbelmiez.de\/index.php\/wp-json\/wp\/v2\/categories?post=3011"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/strubbelmiez.de\/index.php\/wp-json\/wp\/v2\/tags?post=3011"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}